{"id":83196,"date":"2018-06-29T08:41:32","date_gmt":"2018-06-29T08:41:32","guid":{"rendered":"https:\/\/guruvet.com\/?p=83196"},"modified":"2018-06-29T08:41:32","modified_gmt":"2018-06-29T08:41:32","slug":"dicas-controlo-de-caixa","status":"publish","type":"post","link":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/","title":{"rendered":"Dicas para fazer um controlo de caixa eficiente"},"content":{"rendered":"<p>O fluxo de caixa n\u00e3o \u00e9 mais do que a movimenta\u00e7\u00e3o de dinheiro dentro da sua cl\u00ednica veterin\u00e1ria: quanto recebeu e quanto pagou. Em pequenas empresas este controlo de caixa \u00e9 a base operacional de toda a gest\u00e3o financeira e por isso deve ser feito diariamente para que que ser exato.<\/p>\n<p>O controlo de caixa \u00e9 um processo e, de prefer\u00eancia, deve ser realizado sempre pela mesma pessoa. \u00c9 indispens\u00e1vel para a realiza\u00e7\u00e3o de uma boa gest\u00e3o e manuten\u00e7\u00e3o da sa\u00fade financeira da empresa e, a pensar nisso, selecionamos aqui algumas dicas que podem ser \u00fateis para controlar mais facilmente a caixa da sua cl\u00ednica:<\/p>\n<h4><strong>Controle o saldo inicial com aten\u00e7\u00e3o<\/strong><\/h4>\n<p>O controlo de caixa di\u00e1rio inicia com o saldo que tem na caixa da empresa no momento da abertura, muitas vezes chamado de \u201cfundo de maneio\u201d. \u00c9 a partir deste saldo que ser\u00e3o somados ou subtra\u00eddos valores ao longo do dia e \u00e9 por isso que o mesmo deve ser contabilizado com aten\u00e7\u00e3o, para que o valor em caixa seja o real e sem erros desde o in\u00edcio.<\/p>\n<h4><strong>Cuidado com o registo dos pagamentos\/recebimentos<\/strong><\/h4>\n<p>Al\u00e9m de ter que controlar a movimenta\u00e7\u00e3o de dinheiro da caixa, \u00e9 muito importante registar adequadamente de onde ele saiu\/entrou e de que forma: numer\u00e1rio, cart\u00e3o d\u00e9bito, cart\u00e3o de cr\u00e9dito, cheque, transfer\u00eancia banc\u00e1ria, etc. \u00c9 muito comum a falta de registos de entrada e sa\u00edda de dinheiro ou mesmo um registo errado dos lan\u00e7amentos, confundindo, muitas vezes o que foi vendido com o que de facto foi recebido e o que foi comprado com o que realmente foi pago. Sendo, por isso, muito importante registar os valores com algum cuidado e aten\u00e7\u00e3o para n\u00e3o trocar os lan\u00e7amentos.<br \/>\nTamb\u00e9m \u00e9 extremamente importante atribuir corretamente a origem e o destino do dinheiro, isto \u00e9, determinar corretamente se o valor entrou ou saiu da caixa\/da conta banc\u00e1ria (muitas vezes as empresas t\u00eam mais do que uma conta), etc.<\/p>\n<h4><strong>Controle o saldo final no fecho de caixa<\/strong><\/h4>\n<p>Erros no fecho de caixa s\u00e3o muito frequentes e na maioria das vezes nem sequer s\u00e3o detectados. Existem v\u00e1rias raz\u00f5es para que isto suceda, sendo que, se o problema n\u00e3o for corrigido, provocar\u00e1 um efeito \u201cbola de neve\u201d, tendo implica\u00e7\u00f5es diretas na movimenta\u00e7\u00e3o da caixa dos dias posteriores. Por isso, \u00e9 importante fazer uma verifica\u00e7\u00e3o atenta do fecho de caixa para tentar identificar qualquer poss\u00edvel erro de forma a que o mesmo seja corrigido de imediato.<\/p>\n<h4><strong>Cuidado com alguns tipos de transfer\u00eancias e lan\u00e7amentos<\/strong><\/h4>\n<p>Alguns tipos de transfer\u00eancia como dep\u00f3sitos e levantamentos precisam de uma aten\u00e7\u00e3o maior por parte de quem realiza o controlo de caixa, assim como pequenos lan\u00e7amentos que, se lan\u00e7ados de maneira errada, ir\u00e3o gerar confus\u00e3o no seu controlo.<\/p>\n<p>Alguns exemplos:<\/p>\n<ul>\n<li>Dep\u00f3sitos do dinheiro em caixa, com o objetivo de n\u00e3o deixar numer\u00e1rio e cheques dispon\u00edveis na empresa. Estes valores precisam ser lan\u00e7ados, uma vez que mudaram de local f\u00edsico (da caixa para o banco).<\/li>\n<li>\u00c9 comum em pequenas empresas os s\u00f3cios retirarem os seus \u201chonor\u00e1rios\u201d diretamente da caixa e em quantidades fraccionadas. Se este procedimento n\u00e3o for bem registado, ir\u00e1 causar confus\u00e3o na gest\u00e3o da caixa. Ali\u00e1s, \u00e9 muito importante que os s\u00f3cios tenham honor\u00e1rios\/remunera\u00e7\u00f5es com valores espec\u00edficos e que sejam retirados de uma s\u00f3 vez, de prefer\u00eancia em datas definidas, para facilitar o controlo do dinheiro da cl\u00ednica.<\/li>\n<li>No dia-a-dia da cl\u00ednica existem pequenas compras que precisam ser feitas \u00e0 pressa, ou porque acabou um produto de limpeza, os copos de caf\u00e9 ou algum material de escrit\u00f3rio sem aviso pr\u00e9vio ou porque \u00e9 preciso ir aos correios despachar algo ou simplesmente pagar os selos das cartas, etc. \u00c9 o tipo de situa\u00e7\u00e3o onde algum colaborador tira algum \u201cdinheiro\u201d na caixa, e vai a correr comprar ao supermercado ou \u00e0 papelaria mais pr\u00f3xima. O problema \u00e9 que, por ser um pagamento pequeno, na maioria das vezes, n\u00e3o \u00e9 documentado correctamente, no entanto \u00e9 importante o suficiente para impossibilitar um correto fecho de caixa.<\/li>\n<\/ul>\n<h4><strong>Utilize uma ferramenta de gest\u00e3o para o auxiliar<\/strong><\/h4>\n<p>H\u00e1 muita gente que ainda usa um ficheiro de Excel ou caderno para fazer o controlo da caixa da sua cl\u00ednica veterin\u00e1ria, mas \u00e9 muito importante contar com ferramentas que possam facilitar o seu dia-a-dia. Um software de gest\u00e3o confi\u00e1vel \u00e9 a melhor escolha para quem quer elevar o n\u00edvel de gest\u00e3o da sua empresa, pois al\u00e9m de auxiliar no controlo da caixa, cont\u00e9m todas as informa\u00e7\u00f5es sobre vendas, fornecedores, compras, stocks e clientes, isto \u00e9, ter\u00e1 todas as informa\u00e7\u00f5es necess\u00e1rias integradas e armazenadas num s\u00f3 local.<\/p>\n<p><strong>O GuruVet \u00e9 uma ferramenta de gest\u00e3o de cl\u00ednicas e hospitais veterin\u00e1rios, que permite ao utilizador fazer todo o controlo financeiro da sua empresa de forma f\u00e1cil e organizada. Experimente gratuitamente e veja como \u00e9 simples, f\u00e1cil e acess\u00edvel!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O fluxo de caixa n\u00e3o \u00e9 mais do que a movimenta\u00e7\u00e3o de dinheiro dentro da sua cl\u00ednica veterin\u00e1ria: quanto recebeu e quanto pagou. Em pequenas empresas este controlo de caixa \u00e9 a base operacional de toda a gest\u00e3o financeira e por isso deve ser feito diariamente para que que ser exato. O controlo de caixa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":83200,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-83196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dicas para fazer um controlo de caixa eficiente - GuruVet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dicas para fazer um controlo de caixa eficiente - GuruVet\" \/>\n<meta property=\"og:description\" content=\"O fluxo de caixa n\u00e3o \u00e9 mais do que a movimenta\u00e7\u00e3o de dinheiro dentro da sua cl\u00ednica veterin\u00e1ria: quanto recebeu e quanto pagou. Em pequenas empresas este controlo de caixa \u00e9 a base operacional de toda a gest\u00e3o financeira e por isso deve ser feito diariamente para que que ser exato. O controlo de caixa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/\" \/>\n<meta property=\"og:site_name\" content=\"GuruVet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/guruvet.software\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-29T08:41:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/guruvet.com\/wp-content\/uploads\/2018\/06\/controlo-de-caixa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GuruVet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"GuruVet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/dicas-controlo-de-caixa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/dicas-controlo-de-caixa\\\/\"},\"author\":{\"name\":\"GuruVet\",\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/4d6dbb78e4257a52f3891c9938c29347\"},\"headline\":\"Dicas para fazer um controlo de caixa eficiente\",\"datePublished\":\"2018-06-29T08:41:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/dicas-controlo-de-caixa\\\/\"},\"wordCount\":871,\"publisher\":{\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/dicas-controlo-de-caixa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/guruvet.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/controlo-de-caixa.jpg\",\"articleSection\":[\"Dicas\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/dicas-controlo-de-caixa\\\/\",\"url\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/dicas-controlo-de-caixa\\\/\",\"name\":\"Dicas para fazer um controlo de caixa eficiente - GuruVet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/dicas-controlo-de-caixa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/dicas-controlo-de-caixa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/guruvet.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/controlo-de-caixa.jpg\",\"datePublished\":\"2018-06-29T08:41:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/dicas-controlo-de-caixa\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/dicas-controlo-de-caixa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/dicas-controlo-de-caixa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/guruvet.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/controlo-de-caixa.jpg\",\"contentUrl\":\"https:\\\/\\\/guruvet.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/controlo-de-caixa.jpg\",\"width\":1030,\"height\":687,\"caption\":\"dicas controlo de caixa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/dicas-controlo-de-caixa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dicas para fazer um controlo de caixa eficiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/\",\"name\":\"GuruVet\",\"description\":\"Software de Gest\u00e3o Cl\u00ednica Veterin\u00e1ria\",\"publisher\":{\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/#organization\",\"name\":\"GuruVet - Software de Gest\u00e3o para Cl\u00ednicas e Centros Veterin\u00e1rios\",\"url\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/guruvet.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/logoguru-v2.png\",\"contentUrl\":\"https:\\\/\\\/guruvet.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/logoguru-v2.png\",\"width\":388,\"height\":180,\"caption\":\"GuruVet - Software de Gest\u00e3o para Cl\u00ednicas e Centros Veterin\u00e1rios\"},\"image\":{\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/guruvet.software\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXBN4By8qb41-G4wIAfC6Ng\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/guruvet.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/4d6dbb78e4257a52f3891c9938c29347\",\"name\":\"GuruVet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b557dcf3f6ad68b37f873bbc1d81325deea18e05b3191402b5e2fc3e11d1541b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b557dcf3f6ad68b37f873bbc1d81325deea18e05b3191402b5e2fc3e11d1541b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b557dcf3f6ad68b37f873bbc1d81325deea18e05b3191402b5e2fc3e11d1541b?s=96&d=mm&r=g\",\"caption\":\"GuruVet\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dicas para fazer um controlo de caixa eficiente - GuruVet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/","og_locale":"pt_PT","og_type":"article","og_title":"Dicas para fazer um controlo de caixa eficiente - GuruVet","og_description":"O fluxo de caixa n\u00e3o \u00e9 mais do que a movimenta\u00e7\u00e3o de dinheiro dentro da sua cl\u00ednica veterin\u00e1ria: quanto recebeu e quanto pagou. Em pequenas empresas este controlo de caixa \u00e9 a base operacional de toda a gest\u00e3o financeira e por isso deve ser feito diariamente para que que ser exato. O controlo de caixa [&hellip;]","og_url":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/","og_site_name":"GuruVet","article_publisher":"https:\/\/www.facebook.com\/guruvet.software\/","article_published_time":"2018-06-29T08:41:32+00:00","og_image":[{"width":1030,"height":687,"url":"https:\/\/guruvet.com\/wp-content\/uploads\/2018\/06\/controlo-de-caixa.jpg","type":"image\/jpeg"}],"author":"GuruVet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"GuruVet","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/#article","isPartOf":{"@id":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/"},"author":{"name":"GuruVet","@id":"https:\/\/guruvet.com\/pt-pt\/#\/schema\/person\/4d6dbb78e4257a52f3891c9938c29347"},"headline":"Dicas para fazer um controlo de caixa eficiente","datePublished":"2018-06-29T08:41:32+00:00","mainEntityOfPage":{"@id":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/"},"wordCount":871,"publisher":{"@id":"https:\/\/guruvet.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/#primaryimage"},"thumbnailUrl":"https:\/\/guruvet.com\/wp-content\/uploads\/2018\/06\/controlo-de-caixa.jpg","articleSection":["Dicas"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/","url":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/","name":"Dicas para fazer um controlo de caixa eficiente - GuruVet","isPartOf":{"@id":"https:\/\/guruvet.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/#primaryimage"},"image":{"@id":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/#primaryimage"},"thumbnailUrl":"https:\/\/guruvet.com\/wp-content\/uploads\/2018\/06\/controlo-de-caixa.jpg","datePublished":"2018-06-29T08:41:32+00:00","breadcrumb":{"@id":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/#primaryimage","url":"https:\/\/guruvet.com\/wp-content\/uploads\/2018\/06\/controlo-de-caixa.jpg","contentUrl":"https:\/\/guruvet.com\/wp-content\/uploads\/2018\/06\/controlo-de-caixa.jpg","width":1030,"height":687,"caption":"dicas controlo de caixa"},{"@type":"BreadcrumbList","@id":"https:\/\/guruvet.com\/pt-pt\/dicas-controlo-de-caixa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/guruvet.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Dicas para fazer um controlo de caixa eficiente"}]},{"@type":"WebSite","@id":"https:\/\/guruvet.com\/pt-pt\/#website","url":"https:\/\/guruvet.com\/pt-pt\/","name":"GuruVet","description":"Software de Gest\u00e3o Cl\u00ednica Veterin\u00e1ria","publisher":{"@id":"https:\/\/guruvet.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guruvet.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/guruvet.com\/pt-pt\/#organization","name":"GuruVet - Software de Gest\u00e3o para Cl\u00ednicas e Centros Veterin\u00e1rios","url":"https:\/\/guruvet.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/guruvet.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/guruvet.com\/wp-content\/uploads\/2017\/09\/logoguru-v2.png","contentUrl":"https:\/\/guruvet.com\/wp-content\/uploads\/2017\/09\/logoguru-v2.png","width":388,"height":180,"caption":"GuruVet - Software de Gest\u00e3o para Cl\u00ednicas e Centros Veterin\u00e1rios"},"image":{"@id":"https:\/\/guruvet.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/guruvet.software\/","https:\/\/www.youtube.com\/channel\/UCXBN4By8qb41-G4wIAfC6Ng"]},{"@type":"Person","@id":"https:\/\/guruvet.com\/pt-pt\/#\/schema\/person\/4d6dbb78e4257a52f3891c9938c29347","name":"GuruVet","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/b557dcf3f6ad68b37f873bbc1d81325deea18e05b3191402b5e2fc3e11d1541b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b557dcf3f6ad68b37f873bbc1d81325deea18e05b3191402b5e2fc3e11d1541b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b557dcf3f6ad68b37f873bbc1d81325deea18e05b3191402b5e2fc3e11d1541b?s=96&d=mm&r=g","caption":"GuruVet"}}]}},"_links":{"self":[{"href":"https:\/\/guruvet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/83196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guruvet.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guruvet.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guruvet.com\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guruvet.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=83196"}],"version-history":[{"count":0,"href":"https:\/\/guruvet.com\/pt-pt\/wp-json\/wp\/v2\/posts\/83196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guruvet.com\/pt-pt\/wp-json\/wp\/v2\/media\/83200"}],"wp:attachment":[{"href":"https:\/\/guruvet.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=83196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guruvet.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=83196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guruvet.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=83196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}